{"id":3722,"date":"2018-02-04T12:03:00","date_gmt":"2018-02-04T12:03:00","guid":{"rendered":""},"modified":"2023-11-06T10:16:09","modified_gmt":"2023-11-06T10:16:09","slug":"27-1-18-granada-sierra-nevada","status":"publish","type":"post","link":"https:\/\/roadgalaxytouring.com\/index.php\/2018\/02\/04\/27-1-18-granada-sierra-nevada\/","title":{"rendered":"27.1.18 &#8211; Granada | Sierra Nevada"},"content":{"rendered":"<p><a href=\"https:\/\/1.bp.blogspot.com\/-ItHV8dGfdiU\/Wnb1zXvSdOI\/AAAAAAAADxg\/wWf9ALNg3V0Sq_H1IkS5tMvDnuhaUVKUACLcBGAs\/s1600\/20180127_090014.jpg\" style=\"clear: left; float: left; margin-bottom: 1em; margin-right: 1em;\"><img fetchpriority=\"high\" decoding=\"async\" border=\"0\" data-original-height=\"1200\" data-original-width=\"1600\" height=\"240\" src=\"https:\/\/1.bp.blogspot.com\/-ItHV8dGfdiU\/Wnb1zXvSdOI\/AAAAAAAADxg\/wWf9ALNg3V0Sq_H1IkS5tMvDnuhaUVKUACLcBGAs\/s320\/20180127_090014.jpg\" width=\"320\" \/><\/a>Fim de Janeiro e Madrid est\u00e1 um gelo, assim como o resto de Espanha. e a grande vantagem de estar a trabalhar por uma temporada em Madrid \u00e9 que estou no epicentro das estradas que me levam \u00e0s melhores est\u00e2ncias da Pen\u00ednsula.<br \/>\nPirin\u00e9us ou Sierra Nevada?<br \/>\nPara norte, a neve costuma ser melhor mas os hot\u00e9is j\u00e1 estavam cheios ou a pre\u00e7os proibitivos.<br \/>\nPara sul, a incerteza da neve, devido ao vento, com a est\u00e2ncia a ter estado encerrada at\u00e9 quarta-feira.<br \/>\nArriscamos &#8211; o Negrais foi comigo &#8211; e sexta ao final do dia, com o p\u00f4r do sol a acompanhar-nos em grande parte da viagem, rumamos a Granada.<br \/>\nPorqu\u00ea Granada e n\u00e3o a est\u00e2ncia?<br \/>\n<a href=\"https:\/\/2.bp.blogspot.com\/-4AvQPfYcHk0\/Wnb1zVYCjiI\/AAAAAAAADxc\/2pzYlVyF9KQbNsnUkHspWSeq3HOub-HOgCLcBGAs\/s1600\/20180127_103919.jpg\" style=\"clear: left; float: left; margin-bottom: 1em; margin-right: 1em;\"><img decoding=\"async\" border=\"0\" data-original-height=\"1200\" data-original-width=\"1600\" height=\"240\" src=\"https:\/\/2.bp.blogspot.com\/-4AvQPfYcHk0\/Wnb1zVYCjiI\/AAAAAAAADxc\/2pzYlVyF9KQbNsnUkHspWSeq3HOub-HOgCLcBGAs\/s320\/20180127_103919.jpg\" width=\"320\" \/><\/a>Porque era por apenas um dia, porque \u00e9 mais barato, porque h\u00e1 mais anima\u00e7\u00e3o, porque h\u00e1 a <i>Allambra<\/i> e o <i>Casco Viejo<\/i>, porque Espanha, quando neva, se assemelha mais a Portugal do que aos pa\u00edses da Europa Central e \u00e9ramos bem capazes de ficarmos presos no topo da montanha por n\u00e3o se conseguir circular.<br \/>\nAssim, um hotel simp\u00e1tico perto do centro serviu de base ao fim-de-semana pelo sul de Espanha.<br \/>\n\u00c0s 8 da manh\u00e3, todo equipado, subi a Sierra Nevada, por uma estrada que gelava a cada quil\u00f3metro e onde o nevoeiro se adensava.<br \/>\nE ao sair do parque de estacionamento coberto da est\u00e2ncia, o frio e o vento eram tantos que, mesmo antes de ir comprar o forfait, j\u00e1 estava enfiado num caf\u00e9 a tomar um chocolate quente.<br \/>\nAs maquinas dos forfaits apresentavam filas enormes, mais pela demora do sistema do que propriamente pela quantidade de pessoas que se encontravam prontas a esquiar na fria manh\u00e3 de s\u00e1bado.<br \/>\n<a href=\"https:\/\/1.bp.blogspot.com\/-ukWN24GqTAs\/Wnb1zhMuu-I\/AAAAAAAADxk\/mthahV6fB-kqyxpptgsRT6qfV9VTZeh7QCLcBGAs\/s1600\/20180127_142345.jpg\" style=\"clear: left; float: left; margin-bottom: 1em; margin-right: 1em;\"><img decoding=\"async\" border=\"0\" data-original-height=\"1200\" data-original-width=\"1600\" height=\"240\" src=\"https:\/\/1.bp.blogspot.com\/-ukWN24GqTAs\/Wnb1zhMuu-I\/AAAAAAAADxk\/mthahV6fB-kqyxpptgsRT6qfV9VTZeh7QCLcBGAs\/s320\/20180127_142345.jpg\" width=\"320\" \/><\/a>Ao subir no teleski, por entre o nevoeiro, comecei a rever o meu ranking de est\u00e2ncias excelentes quando n\u00e3o se v\u00ea um palmo \u00e0 frente dos olhos: <a href=\"https:\/\/roadgalaxytouring.com\/index.php\/2015\/01\/17\/17-1-15-lech\/\" target=\"_blank\" rel=\"noopener\">Lech<\/a> e <a href=\"https:\/\/www.instagram.com\/p\/BCdxNqRjHlX\/?taken-by=rebelomartins\" target=\"_blank\" rel=\"noopener\">Davos<\/a> est\u00e3o no topo das prefer\u00eancias. Ser\u00e1 que tenho que somar Sierra Nevada?!<br \/>\nNo topo do teleski, uma fronteira e um pa\u00eds novo: o sol raiava por cima das n\u00favens e, n\u00e3o sendo forte o suficiente para aquecer o corpo, a sua luz aquecia a alma!<br \/>\nDuas descidas a tomar o pulso para, logo a seguir, descer a pista negra ao lado da antena.<br \/>\nEstava dado o mote: a partir da\u00ed foi a fundo!<br \/>\nA neve estava dura, com o frio da noite a gelar a cama da superficial e as primeiras descidas foram a arriscar. Mas depois, tudo parecia f\u00e1cil, a grande velocidade, serpenteando os outros esquiadores,&nbsp; saltando nas encostas. Parecia um mi\u00fado no parque infantil!<br \/>\n<a href=\"https:\/\/4.bp.blogspot.com\/-RfvJu8VH7pY\/Wnb10VnJrcI\/AAAAAAAADxo\/RdMXZL28i_YrnQ4E5zm0HjDJAYT9fEgzQCLcBGAs\/s1600\/20180127_170655.jpg\" style=\"clear: left; float: left; margin-bottom: 1em; margin-right: 1em;\"><img loading=\"lazy\" decoding=\"async\" border=\"0\" data-original-height=\"1200\" data-original-width=\"1600\" height=\"240\" src=\"https:\/\/4.bp.blogspot.com\/-RfvJu8VH7pY\/Wnb10VnJrcI\/AAAAAAAADxo\/RdMXZL28i_YrnQ4E5zm0HjDJAYT9fEgzQCLcBGAs\/s320\/20180127_170655.jpg\" width=\"320\" \/><\/a>Quando subi no saca-rabos e depois apanhei a encosta mediterr\u00e2nea parei:&nbsp; tirei o capacete e os \u00f3culos e fiquei a olhar o mar ao fundo.<br \/>\nAqui a alma aqueceu; muito: Marrocos ao fundo e o sonho de tantas viagens de tantas est\u00f3rias. Sorria, cantava, estava feliz.<br \/>\nDesde 2015 que n\u00e3o me divertia tanto na neve.<br \/>\nUma cerveja geladinha baixou os n\u00edveis de adrenalina e, na falta de tremo\u00e7os, uma sopa ajudou a compor a coisa.<br \/>\nDepois de almo\u00e7o, j\u00e1 com a est\u00eancia cheia de gente e com a visibilidade a diminuir devido aos flocos que ca\u00edam indeterminadamente do c\u00e9u, decidi ir embora. Fiquei com as melhores recorda\u00e7\u00f5es na mem\u00f3ria.<br \/>\nOs 30 e poucos quil\u00f3metros que separam a est\u00e2ncia de Granada foram feitos ainda com a adrenalina do ski, acompanhados pela Rock FM e pelo <a href=\"https:\/\/www.youtube.com\/watch?v=a7a35GnfPTc\" target=\"_blank\" rel=\"noopener\">Chris Isaak<\/a>. Yeahhh!!!!<br \/>\nEm Granada, o centro hist\u00f3rico &#8211; com a bandeira portuguesa, juntamente com a espanhola e a da andaluzia, no topo da Allambra &#8211; as taparias, com muitas can\u00e3s, vi\u00f1o e genebra fizeram o dia&nbsp; terminar em grande.<br \/>\nDeseja um fim-de-semana assim?! Na Ag\u00eancia Para\u00edso tratam de tudo, aproveite!<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fim de Janeiro e Madrid est\u00e1 um gelo, assim como o resto de Espanha. e a grande vantagem de estar a trabalhar por uma temporada em Madrid \u00e9 que estou no epicentro das estradas que me levam \u00e0s melhores est\u00e2ncias da Pen\u00ednsula. Pirin\u00e9us ou Sierra Nevada? Para norte, a neve costuma ser melhor mas os [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":4045,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[146,88,148,149,145,119,46,147,96],"tags":[],"featured_image_src":{"landsacpe":["https:\/\/roadgalaxytouring.com\/wp-content\/uploads\/2018\/02\/20180127_090014-1024x445.jpg",1024,445,true],"list":["https:\/\/roadgalaxytouring.com\/wp-content\/uploads\/2018\/02\/20180127_090014-463x348.jpg",463,348,true],"medium":["https:\/\/roadgalaxytouring.com\/wp-content\/uploads\/2018\/02\/20180127_090014-300x225.jpg",300,225,true],"full":["https:\/\/roadgalaxytouring.com\/wp-content\/uploads\/2018\/02\/20180127_090014.jpg",1024,768,false]},"_links":{"self":[{"href":"https:\/\/roadgalaxytouring.com\/index.php\/wp-json\/wp\/v2\/posts\/3722"}],"collection":[{"href":"https:\/\/roadgalaxytouring.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roadgalaxytouring.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/roadgalaxytouring.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/roadgalaxytouring.com\/index.php\/wp-json\/wp\/v2\/comments?post=3722"}],"version-history":[{"count":1,"href":"https:\/\/roadgalaxytouring.com\/index.php\/wp-json\/wp\/v2\/posts\/3722\/revisions"}],"predecessor-version":[{"id":4049,"href":"https:\/\/roadgalaxytouring.com\/index.php\/wp-json\/wp\/v2\/posts\/3722\/revisions\/4049"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roadgalaxytouring.com\/index.php\/wp-json\/wp\/v2\/media\/4045"}],"wp:attachment":[{"href":"https:\/\/roadgalaxytouring.com\/index.php\/wp-json\/wp\/v2\/media?parent=3722"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roadgalaxytouring.com\/index.php\/wp-json\/wp\/v2\/categories?post=3722"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roadgalaxytouring.com\/index.php\/wp-json\/wp\/v2\/tags?post=3722"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}