{"id":3728,"date":"2017-04-29T09:00:00","date_gmt":"2017-04-29T09:00:00","guid":{"rendered":"https:\/\/roadgalaxytouring.com\/index.php\/2017\/04\/29\/26-4-17-erg-ouzina-merzouga\/"},"modified":"2017-04-29T09:00:00","modified_gmt":"2017-04-29T09:00:00","slug":"26-4-17-erg-ouzina-merzouga","status":"publish","type":"post","link":"https:\/\/roadgalaxytouring.com\/index.php\/2017\/04\/29\/26-4-17-erg-ouzina-merzouga\/","title":{"rendered":"26.4.17 &#8211; Erg Ouzina | Merzouga"},"content":{"rendered":"<p><\/p>\n<div style=\"clear: both; text-align: center;\">\n<a href=\"https:\/\/3.bp.blogspot.com\/-xzBvsgdDxOg\/WQRV8QRqBiI\/AAAAAAAADoM\/nbSYIn5vxbcc2Vcn3-BGoG7QFl6Fj0JeACLcB\/s1600\/IMG_0363.JPG\" style=\"clear: left; float: left; margin-bottom: 1em; margin-right: 1em;\"><img fetchpriority=\"high\" decoding=\"async\" border=\"0\" height=\"180\" src=\"https:\/\/3.bp.blogspot.com\/-xzBvsgdDxOg\/WQRV8QRqBiI\/AAAAAAAADoM\/nbSYIn5vxbcc2Vcn3-BGoG7QFl6Fj0JeACLcB\/s320\/IMG_0363.JPG\" width=\"320\" \/><\/a><\/div>\n<p><a href=\"https:\/\/1.bp.blogspot.com\/-POdBrSh1yy8\/WQRVrop8yZI\/AAAAAAAADoE\/FKS6I2nLeCEwSnOwak5blB2YOF6MSbB_ACLcB\/s1600\/20170426_112501.jpg\" style=\"clear: left; float: left; margin-bottom: 1em; margin-right: 1em;\"><img decoding=\"async\" border=\"0\" height=\"240\" src=\"https:\/\/1.bp.blogspot.com\/-POdBrSh1yy8\/WQRVrop8yZI\/AAAAAAAADoE\/FKS6I2nLeCEwSnOwak5blB2YOF6MSbB_ACLcB\/s320\/20170426_112501.jpg\" width=\"320\" \/><\/a>Pouco mais de 50 km separavam Erg Ouzina de Merzouga, e o plano seria percorrer essa dist\u00e2ncia de manh\u00e3 para, de tarde, descansarmos e recuperar as motos no mec\u00e2nico.<br \/>\nAntes da sa\u00edda ainda deu tempo para caminhar pelo Erg e v\u00ear a marca que as cobras deixam na areia, um ss perfeito e indel\u00e9vel.<br \/>\nO albergue, mesmo no meio da pista do Dakar, era o spot perfeito para ver, logo de manh\u00e3zinha, os aventureiros a fazerem-se \u00e0s dificuldades do deserto; e eram muitos em moto e 4&#215;4, apoiados por carros de assist\u00eancia que transportavam pneus, gasolina, a bagagem para as motos irem o mais leves poss\u00edveis. Tudo aquilo que n\u00f3s n\u00e3o t\u00ednhamos.<\/p>\n<div style=\"clear: both; text-align: center;\">\n<a href=\"https:\/\/2.bp.blogspot.com\/-cytgbqi185g\/WQRV-PzIWmI\/AAAAAAAADoU\/p2DfTXGhfDMKb3wSYi0BxtJ1I1qCh53BACLcB\/s1600\/IMG_0365.JPG\" style=\"clear: left; float: left; margin-bottom: 1em; margin-right: 1em;\"><img decoding=\"async\" border=\"0\" height=\"180\" src=\"https:\/\/2.bp.blogspot.com\/-cytgbqi185g\/WQRV-PzIWmI\/AAAAAAAADoU\/p2DfTXGhfDMKb3wSYi0BxtJ1I1qCh53BACLcB\/s320\/IMG_0365.JPG\" width=\"320\" \/><\/a><\/div>\n<p>Na companhia do Zaid, vi os meus companheiros atravessarem&nbsp; dunas e percorrer r\u00e1pidamente as longas rectas empoeiradas.<br \/>\nA chega a Merzouga foi como a chegada a uma cidade acabada de ser bombardeada por napalm: era tanto o vento e o p\u00f3 que circulava no ar que os edif\u00edcios apareciam como uma sombra.<br \/>\nNa minha moto tinham que tentar compor a embraiagem, na do Pedro, mudar a c\u00e2mera de ar, na do Fernando foi era necess\u00e1rio soldar os apoios do guarda lamas traseiro. Ficou tudo ao cuidado do Mustafa do Team Gordito.<br \/>\n<a href=\"https:\/\/2.bp.blogspot.com\/-j0rCDJQncNw\/WQRV9YOY67I\/AAAAAAAADoQ\/lb9CuYzn-gcoKFtk3GSOSl5Hz52-Moa9QCLcB\/s1600\/IMG_0381.JPG\" style=\"clear: left; float: left; margin-bottom: 1em; margin-right: 1em;\"><img loading=\"lazy\" decoding=\"async\" border=\"0\" height=\"180\" src=\"https:\/\/2.bp.blogspot.com\/-j0rCDJQncNw\/WQRV9YOY67I\/AAAAAAAADoQ\/lb9CuYzn-gcoKFtk3GSOSl5Hz52-Moa9QCLcB\/s320\/IMG_0381.JPG\" width=\"320\" \/><\/a>E o Zaid connosco&#8230;<br \/>\nA tarde foi passada na piscina do hotel, estrategicamente colocada na base das dunas. Com o vento que estava, n\u00e3o \u00e9 dif\u00edcil de perceber que a \u00e1gua mais parecia a da zona de rebenta\u00e7\u00e3o de uma qualquer praia do algarve!<br \/>\n<a href=\"https:\/\/1.bp.blogspot.com\/-2h4TYQf8oM8\/WQRVswqwXOI\/AAAAAAAADoI\/1df9nNOyZhYVup1wgV2eKySnEti7_8ZPgCLcB\/s1600\/20170426_144950.jpg\" style=\"clear: left; float: left; margin-bottom: 1em; margin-right: 1em;\"><img loading=\"lazy\" decoding=\"async\" border=\"0\" height=\"240\" src=\"https:\/\/1.bp.blogspot.com\/-2h4TYQf8oM8\/WQRVswqwXOI\/AAAAAAAADoI\/1df9nNOyZhYVup1wgV2eKySnEti7_8ZPgCLcB\/s320\/20170426_144950.jpg\" width=\"320\" \/><\/a>Quando o sol se punha foi altura de ir buscar as motos e acertar contas: 400 euros de reboque do deserto para Merzouga, 225 euros de consertar a minha embraiagem, 80 euros do transporte de 4&#215;4 at\u00e9 \u00e0 moto, 15 euros de mudar a c\u00e2mera de ar do pneu do Pedro e 60 euros para o irm\u00e3o do Zaid, que ficou umas horas ao lado da moto.<br \/>\nQuando tudo foi pago ao Zaid, afastou-se.<br \/>\nOs mu\u00e7ulmanos assentadores de azulejos t\u00eam o h\u00e1bito de colocar um ao contr\u00e1rio para a obra n\u00e3o ficar perfeita. Fazem isso porque pensam que s\u00f3 Deus \u00e9 que pode fazer uma obra perfeita.<br \/>\nTalvez por isso na minha moto faltava um parafuso de todas as pe\u00e7as que foram retiradas; era para n\u00e3o ficar perfeito!<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pouco mais de 50 km separavam Erg Ouzina de Merzouga, e o plano seria percorrer essa dist\u00e2ncia de manh\u00e3 para, de tarde, descansarmos e recuperar as motos no mec\u00e2nico. Antes da sa\u00edda ainda deu tempo para caminhar pelo Erg e v\u00ear a marca que as cobras deixam na areia, um ss perfeito e indel\u00e9vel. O [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[41,172,149,171,173],"tags":[],"featured_image_src":{"landsacpe":false,"list":false,"medium":false,"full":false},"_links":{"self":[{"href":"https:\/\/roadgalaxytouring.com\/index.php\/wp-json\/wp\/v2\/posts\/3728"}],"collection":[{"href":"https:\/\/roadgalaxytouring.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roadgalaxytouring.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/roadgalaxytouring.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/roadgalaxytouring.com\/index.php\/wp-json\/wp\/v2\/comments?post=3728"}],"version-history":[{"count":0,"href":"https:\/\/roadgalaxytouring.com\/index.php\/wp-json\/wp\/v2\/posts\/3728\/revisions"}],"wp:attachment":[{"href":"https:\/\/roadgalaxytouring.com\/index.php\/wp-json\/wp\/v2\/media?parent=3728"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roadgalaxytouring.com\/index.php\/wp-json\/wp\/v2\/categories?post=3728"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roadgalaxytouring.com\/index.php\/wp-json\/wp\/v2\/tags?post=3728"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}