{"id":3760,"date":"2016-05-20T07:09:00","date_gmt":"2016-05-20T07:09:00","guid":{"rendered":"https:\/\/roadgalaxytouring.com\/index.php\/2016\/05\/20\/rebelo-martins-no-adventure-days-2016\/"},"modified":"2016-05-20T07:09:00","modified_gmt":"2016-05-20T07:09:00","slug":"rebelo-martins-no-adventure-days-2016","status":"publish","type":"post","link":"https:\/\/roadgalaxytouring.com\/index.php\/2016\/05\/20\/rebelo-martins-no-adventure-days-2016\/","title":{"rendered":"Rebelo Martins no Adventure Days 2016"},"content":{"rendered":"<div dir=\"ltr\" style=\"text-align: left;\">\n<div style=\"clear: both; text-align: center;\">\n<a href=\"https:\/\/3.bp.blogspot.com\/-WcKjVmJpoeI\/Vz64BOcN8rI\/AAAAAAAABlw\/tDun6l9o9WssHiDdkXsDk2iSQlcuiG7TACLcB\/s1600\/11188258_1640680519488435_475465530018401988_n.jpg\" style=\"clear: left; float: left; margin-bottom: 1em; margin-right: 1em;\"><img fetchpriority=\"high\" decoding=\"async\" border=\"0\" height=\"213\" src=\"https:\/\/3.bp.blogspot.com\/-WcKjVmJpoeI\/Vz64BOcN8rI\/AAAAAAAABlw\/tDun6l9o9WssHiDdkXsDk2iSQlcuiG7TACLcB\/s320\/11188258_1640680519488435_475465530018401988_n.jpg\" width=\"320\" \/><\/a><\/div>\n<p>Jo\u00e3o Rebelo Martins vai participar, este fim-de-semana, no Adventure Days 2016. Em moto, s\u00e3o 270 Km de aventura, emo\u00e7\u00e3o e adrenalina no ribatejo, em torno da Ribeira do Alviela.<br \/>O piloto que corre com as cores da eni, Vida Econ\u00f3mica, fluidotronica, Loba, Cl\u00ednica Pardelhas, Norfer, Eumel e as parcerias com a Nau Helmets, Hama Portugal, Motor Vision, Alpinestrars, Mitas, Ag\u00eancia Para\u00edso, Monte Campo, Quinta do Estanho e Oakley, na apresenta\u00e7\u00e3o que fez do seu projecto desportivo para 2016, referiu que iria continuar as aventuras em motorismo, sendo o Adventure Days a primeira delas.<br \/>Para Rebelo Martins \u201c depois da minha primeira ida ao Egipto, em 2014, e tudo o que realizei e concretizei em 2015, \u00e9 impens\u00e1vel n\u00e3o abranger o motorismo na minha carreira e n\u00e3o envolver os patrocinadores e parceiros nesta actividade. \u00c9 a vertente n\u00e3o competitiva do TT, mas que fa\u00e7o com grande esp\u00edrito de aventura e em busca de locais lind\u00edssimos e est\u00f3rias que aumentam a hist\u00f3ria da vida\u201d.<br \/>O Adventure Days \u00e9 um passeio destinado a levar motos trails e maxi-trails ao seu habitat natural, num ambiente de grande conv\u00edvio e camaradagem. \u00c9 uma associa\u00e7\u00e3o entre lazer e aventura, entre pessoas de todo o pa\u00eds que partilham a paix\u00e3o pelas motos e pelas viagens aventura. <\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Jo\u00e3o Rebelo Martins vai participar, este fim-de-semana, no Adventure Days 2016. Em moto, s\u00e3o 270 Km de aventura, emo\u00e7\u00e3o e adrenalina no ribatejo, em torno da Ribeira do Alviela.O piloto que corre com as cores da eni, Vida Econ\u00f3mica, fluidotronica, Loba, Cl\u00ednica Pardelhas, Norfer, Eumel e as parcerias com a Nau Helmets, Hama Portugal, Motor [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"featured_image_src":{"landsacpe":false,"list":false,"medium":false,"full":false},"_links":{"self":[{"href":"https:\/\/roadgalaxytouring.com\/index.php\/wp-json\/wp\/v2\/posts\/3760"}],"collection":[{"href":"https:\/\/roadgalaxytouring.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roadgalaxytouring.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/roadgalaxytouring.com\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/roadgalaxytouring.com\/index.php\/wp-json\/wp\/v2\/comments?post=3760"}],"version-history":[{"count":0,"href":"https:\/\/roadgalaxytouring.com\/index.php\/wp-json\/wp\/v2\/posts\/3760\/revisions"}],"wp:attachment":[{"href":"https:\/\/roadgalaxytouring.com\/index.php\/wp-json\/wp\/v2\/media?parent=3760"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roadgalaxytouring.com\/index.php\/wp-json\/wp\/v2\/categories?post=3760"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roadgalaxytouring.com\/index.php\/wp-json\/wp\/v2\/tags?post=3760"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}