{"id":3809,"date":"2015-07-29T19:39:00","date_gmt":"2015-07-29T19:39:00","guid":{"rendered":"https:\/\/roadgalaxytouring.com\/index.php\/2015\/07\/29\/29-7-15-porto-zurich\/"},"modified":"2015-07-29T19:39:00","modified_gmt":"2015-07-29T19:39:00","slug":"29-7-15-porto-zurich","status":"publish","type":"post","link":"https:\/\/roadgalaxytouring.com\/index.php\/2015\/07\/29\/29-7-15-porto-zurich\/","title":{"rendered":"29.7.15 &#8211; Porto | Zurich"},"content":{"rendered":"<div style=\"clear: both; text-align: center;\">\n<a href=\"http:\/\/4.bp.blogspot.com\/-8urtsvtrTU8\/VbiBTdJDSjI\/AAAAAAAACiU\/onMrJ7kzWZU\/s1600\/viagem%2Baustralia.tif\" style=\"clear: left; float: left; margin-bottom: 1em; margin-right: 1em;\"><img fetchpriority=\"high\" decoding=\"async\" border=\"0\" height=\"176\" src=\"http:\/\/4.bp.blogspot.com\/-8urtsvtrTU8\/VbiBTdJDSjI\/AAAAAAAACiU\/onMrJ7kzWZU\/s320\/viagem%2Baustralia.tif\" width=\"320\" \/><\/a><\/div>\n<p>Dormir pouco, trabalhar muito: deixar tudo pronto na Loba para que 25 dias de aus\u00eancia do pa\u00eds n\u00e3o se fa\u00e7am sentir.<br \/>\nFazer a mala, empurrar a roupa l\u00e1 para dentro. Deixei as barbatanas mas coloquei t-shirts suficientes para tanto tempo. Metade da viagem \u00e9 com inverno rigoroso. Outra metade \u00e9 ver\u00e3o tropical.<br \/>\nAs m\u00e1quinas da Liquid Image e os acess\u00f3rios da Hama, est\u00e3o nas Monte Campo. Tudo condicionado. Tudo compartimentado.<br \/>\nO Domingos levou-me ao aeroporto e a Ag\u00eancia Para\u00edso, como sempre, fez um trabalho fant\u00e1stico. Passados poucos minutos estava no avi\u00e3o, sem antes ter comprado um livro de Tolstoi &#8211; Morte de Ivan Ilitch, queria o \u00faltimo de Le Carr\u00e9 mas n\u00e3o tinham &#8211; e uma Moleskine verde que ir\u00e1 ser o caderno da viagem.<br \/>\nO voo da TAP para Zurich correu normalmente. Como companheiros de fila tive um casal com muita pinta, simpatiquissimo: ela loura de olhos azuis, su\u00ed\u00e7a; ele a\u00e7oreano, das Flores, filho de uma angola e com uma grande cabeleira \u00e0 reggea artist.<br \/>\nNeste momento o <i>Aussie Connection <\/i>est\u00e1 reunida em St. Gallen: churrasco, Super Bock e Gazela.<br \/>\nA minha mala tem que ser reduzida e vou ter que lavar a roupa a meio da viagem, tenho que comprar uns batons para o trekking e esqueci-me do pijama &#8211; sim M\u00e3e! um drama que tenho desde meados dos anos 90, com pijamas comprados em tudo quanto \u00e9 s\u00edtio.<br \/>\nCome\u00e7ou a grande aventura: Austr\u00e1lia aqui vamos n\u00f3s!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dormir pouco, trabalhar muito: deixar tudo pronto na Loba para que 25 dias de aus\u00eancia do pa\u00eds n\u00e3o se fa\u00e7am sentir. Fazer a mala, empurrar a roupa l\u00e1 para dentro. Deixei as barbatanas mas coloquei t-shirts suficientes para tanto tempo. Metade da viagem \u00e9 com inverno rigoroso. Outra metade \u00e9 ver\u00e3o tropical. As m\u00e1quinas da [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[164,377,41,388,94,481,74,480,479],"tags":[],"featured_image_src":{"landsacpe":false,"list":false,"medium":false,"full":false},"_links":{"self":[{"href":"https:\/\/roadgalaxytouring.com\/index.php\/wp-json\/wp\/v2\/posts\/3809"}],"collection":[{"href":"https:\/\/roadgalaxytouring.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roadgalaxytouring.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/roadgalaxytouring.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/roadgalaxytouring.com\/index.php\/wp-json\/wp\/v2\/comments?post=3809"}],"version-history":[{"count":0,"href":"https:\/\/roadgalaxytouring.com\/index.php\/wp-json\/wp\/v2\/posts\/3809\/revisions"}],"wp:attachment":[{"href":"https:\/\/roadgalaxytouring.com\/index.php\/wp-json\/wp\/v2\/media?parent=3809"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roadgalaxytouring.com\/index.php\/wp-json\/wp\/v2\/categories?post=3809"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roadgalaxytouring.com\/index.php\/wp-json\/wp\/v2\/tags?post=3809"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}