{"id":3820,"date":"2015-06-16T17:47:00","date_gmt":"2015-06-16T17:47:00","guid":{"rendered":"https:\/\/roadgalaxytouring.com\/index.php\/2015\/06\/16\/16-6-15-viena-hallstatt-salzburgo\/"},"modified":"2015-06-16T17:47:00","modified_gmt":"2015-06-16T17:47:00","slug":"16-6-15-viena-hallstatt-salzburgo","status":"publish","type":"post","link":"https:\/\/roadgalaxytouring.com\/index.php\/2015\/06\/16\/16-6-15-viena-hallstatt-salzburgo\/","title":{"rendered":"16.6.15 &#8211; Viena | Hallstatt | Salzburgo"},"content":{"rendered":"<p><a href=\"http:\/\/4.bp.blogspot.com\/-5AG6XIaFpss\/VYBgfO-EmjI\/AAAAAAAACWM\/TXnpLgkH0Lw\/s1600\/Hallstatt.jpg\" style=\"clear: left; float: left; margin-bottom: 1em; margin-right: 1em;\"><img fetchpriority=\"high\" decoding=\"async\" border=\"0\" height=\"168\" src=\"http:\/\/4.bp.blogspot.com\/-5AG6XIaFpss\/VYBgfO-EmjI\/AAAAAAAACWM\/TXnpLgkH0Lw\/s320\/Hallstatt.jpg\" width=\"320\" \/><\/a>Viena acordou fria e a amea\u00e7ar chuva. Por causa disso n\u00e3o abri a capota do carro e fui em direc\u00e7\u00e3o a Salzburgo, via Hallstatt, na regi\u00e3o de Salzkammergut.<br \/>\nFoi a primeira vez que viajei com a capota do carro fechada e a sensa\u00e7\u00e3o de conforto \u00e9 enorme dada a boa insonoriza\u00e7\u00e3o. T\u00e3o boa que, tamb\u00e9m pela primeira vez, tive que ligar o r\u00e1dio para n\u00e3o adormecer.<br \/>\n<a href=\"http:\/\/1.bp.blogspot.com\/-xz2Vheokg9Y\/VYBgkxFa3KI\/AAAAAAAACWc\/OcRAvsblSh4\/s1600\/salzsburg2.jpg\" style=\"clear: left; float: left; margin-bottom: 1em; margin-right: 1em;\"><img decoding=\"async\" border=\"0\" height=\"181\" src=\"http:\/\/1.bp.blogspot.com\/-xz2Vheokg9Y\/VYBgkxFa3KI\/AAAAAAAACWc\/OcRAvsblSh4\/s320\/salzsburg2.jpg\" width=\"320\" \/><\/a>Quando sa\u00ed da auto-estrada e, mesmo com nevoeiro e aquela morrinha chata, comecei a ver o que me esperava, decidi abrir a capota e deixar os Alpes entrarem no carro. Literalmente! O meu amigo Andr\u00e9 Prata tinha-me dito que esta regi\u00e3o era uma p\u00e9rola por descobrir no centro da Europa. N\u00e3o imaginava que fosse t\u00e3o bonita.<br \/>\nFloresta virgem que desce abruptamente at\u00e9 ao lago Traunsee, com uns veleiros e um comboio a passar mesmo junto \u00e0 \u00e1gua; parecendo um cen\u00e1rio de conto de fadas.<br \/>\n<a href=\"http:\/\/4.bp.blogspot.com\/-DgmnNwkFK0A\/VYBghLjJPlI\/AAAAAAAACWU\/fQ8CmyHydRo\/s1600\/salzsburg.jpg\" style=\"clear: left; float: left; margin-bottom: 1em; margin-right: 1em;\"><img decoding=\"async\" border=\"0\" height=\"168\" src=\"http:\/\/4.bp.blogspot.com\/-DgmnNwkFK0A\/VYBghLjJPlI\/AAAAAAAACWU\/fQ8CmyHydRo\/s320\/salzsburg.jpg\" width=\"320\" \/><\/a>Chegado a Hallstatt &#8211; uma pequena aldeia muito t\u00edpica noutro lago \u2013, com casinhas coloridas e uma igreja em cima da \u00e1gua e outra ao lado de uma cascata, fiquei embasbacado. T\u00e3o lindo! Ali percebi melhor o porqu\u00ea de uma amiga, m\u00e9dica, andar a estudar alem\u00e3o para poder ir trabalhar para o Tirol do Sul. Deve ser fant\u00e1stico poder viver e trabalhar num ambiente que inspira tanta paz. Ent\u00e3o no inverno, com a neve, deve ser de cortar a respira\u00e7\u00e3o.<br \/>\n<a href=\"http:\/\/4.bp.blogspot.com\/-qBSvXNSwOBY\/VYBgocklFcI\/AAAAAAAACWk\/jB7boyImsYo\/s1600\/maps.png\" style=\"clear: left; float: left; margin-bottom: 1em; margin-right: 1em;\"><img loading=\"lazy\" decoding=\"async\" border=\"0\" height=\"96\" src=\"http:\/\/4.bp.blogspot.com\/-qBSvXNSwOBY\/VYBgocklFcI\/AAAAAAAACWk\/jB7boyImsYo\/s320\/maps.png\" width=\"320\" \/><\/a>Em Hallstatt, pelo segundo dia consecutivo, fiquei todo encharcado e o regresso j\u00e1 foi feito com a capota fechada.<br \/>\nNo carrocel de curvas que se seguiu, com a estrada molhada, tirei partido do Quattro. Que maravilha, que divers\u00e3o, pura adrenalina. Aquela sensa\u00e7\u00e3o t\u00e3o boa de entrar nas curvas com o carro a escorregar e, quando acelero, ele vai para onde apontei, com a traseira um pouquinho solta. L\u00e1 se foi o or\u00e7amento para gasolina\u2026 mas se n\u00e3o fosse para isto, mais valia ter alugado um Dacia.<br \/>\nDepois de tanta emo\u00e7\u00e3o, cheguei a Salzburgo. O meu hotel \u00e9 do lado novo da cidade e, por isso, fui a p\u00e9, atravessei uma das pontes e comecei a ver a cidade de baixo para cima.<br \/>\nNa zona comercial, apinhada de asi\u00e1ticos que se passeiam de m\u00e1quina fotogr\u00e1fica e tudo quanto \u00e9 sacos da Vuitton, H\u00e9rmes, Gucci, Prada, Chanel e outras coisas do g\u00e9nero, entrei na Red Bull World. Entre todo o merchandising poss\u00edvel e imagin\u00e1rio, o Red Bull RB 7 de\u2026 Vettel. Aqui homenageiam-se os desportistas que honraram a equipa e que trouxeram t\u00edtulos, mesmo quando v\u00e3o para a equipa advers\u00e1ria; mentalidade desportista.<br \/>\nDepois vi a catedral, e a cripta. Salzburgo foi feita a r\u00e9gua e esquadro, sob a luz do sol e da lua. Por aqui tocou Mozart e era passeio obrigat\u00f3rio dos Imperadores e do Bispado Europeu. Que segredos ter\u00e1 esta cidade escondidos nas suas pedras, tornando-a t\u00e3o importante ao longo dos s\u00e9culos?!<br \/>\nDepois foi tempo de subir ao castelo. No funicular pediam 11 euros pela viagem. Ora, eu n\u00e3o ando no Gin\u00e1sio do Rainha a puxar pelo f\u00edsico para, quando tiver que escalar uma parede, ter que pagar 11 euros! Foi a p\u00e9, subi as escadinhas todas at\u00e9 l\u00e1 cima; confesso que no final do primeiro lan\u00e7o j\u00e1 estava arrependido de n\u00e3o ter pago os 11 euros mas n\u00e3o ia dar parte de fraco.<br \/>\nChegado l\u00e1 cima, ganhei um pr\u00e9mio: tive o direito a pagar 8 euros para entrar no castelo. Roguei-lhes uma praga!<br \/>\nNo castelo, al\u00e9m da vista magn\u00edfica, fiquei a conhecer um pouco a hist\u00f3ria e a import\u00e2ncia de Salzburgo ao longo dos s\u00e9culos. Retive uma data curiosa: 1495. Nesta altura o castelo ainda s\u00f3 tinha sofrido tr\u00eas aumentos, tendo outros tantos depois desta data. Tudo para defender o monte, numa perspectiva meramente b\u00e9lica.<br \/>\nPensei que, nessa mesma altura, em Portugal, apenas se pensava em construir barcos e formar marinheiros, com base na ci\u00eancia, para irem descobrir o mundo e oferec\u00ea-lo \u00e0 Europa. Salve Agostinho da Silva. &nbsp; &nbsp; <\/p>\n<div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Viena acordou fria e a amea\u00e7ar chuva. Por causa disso n\u00e3o abri a capota do carro e fui em direc\u00e7\u00e3o a Salzburgo, via Hallstatt, na regi\u00e3o de Salzkammergut. Foi a primeira vez que viajei com a capota do carro fechada e a sensa\u00e7\u00e3o de conforto \u00e9 enorme dada a boa insonoriza\u00e7\u00e3o. T\u00e3o boa que, tamb\u00e9m [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[97,538,387,41,542,227,532,546,545,52,543,544,540,539,534,541],"tags":[],"featured_image_src":{"landsacpe":false,"list":false,"medium":false,"full":false},"_links":{"self":[{"href":"https:\/\/roadgalaxytouring.com\/index.php\/wp-json\/wp\/v2\/posts\/3820"}],"collection":[{"href":"https:\/\/roadgalaxytouring.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roadgalaxytouring.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/roadgalaxytouring.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/roadgalaxytouring.com\/index.php\/wp-json\/wp\/v2\/comments?post=3820"}],"version-history":[{"count":0,"href":"https:\/\/roadgalaxytouring.com\/index.php\/wp-json\/wp\/v2\/posts\/3820\/revisions"}],"wp:attachment":[{"href":"https:\/\/roadgalaxytouring.com\/index.php\/wp-json\/wp\/v2\/media?parent=3820"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roadgalaxytouring.com\/index.php\/wp-json\/wp\/v2\/categories?post=3820"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roadgalaxytouring.com\/index.php\/wp-json\/wp\/v2\/tags?post=3820"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}