{"id":3828,"date":"2015-06-02T08:57:00","date_gmt":"2015-06-02T08:57:00","guid":{"rendered":"https:\/\/roadgalaxytouring.com\/index.php\/2015\/06\/02\/por-estes-dias\/"},"modified":"2015-06-02T08:57:00","modified_gmt":"2015-06-02T08:57:00","slug":"por-estes-dias","status":"publish","type":"post","link":"https:\/\/roadgalaxytouring.com\/index.php\/2015\/06\/02\/por-estes-dias\/","title":{"rendered":"Por estes dias&#8230;"},"content":{"rendered":"<p><a href=\"http:\/\/1.bp.blogspot.com\/-CEKi9QQymz0\/VW1vyN2VsCI\/AAAAAAAACNA\/FQOViTZorig\/s1600\/Mergulho%2B1.jpg\" style=\"clear: left; float: left; margin-bottom: 1em; margin-right: 1em;\"><img fetchpriority=\"high\" decoding=\"async\" border=\"0\" height=\"240\" src=\"http:\/\/1.bp.blogspot.com\/-CEKi9QQymz0\/VW1vyN2VsCI\/AAAAAAAACNA\/FQOViTZorig\/s320\/Mergulho%2B1.jpg\" width=\"320\" \/><\/a>&#8230;a moto tem ficado parada na garagem e o trabalho tem crescido na <a href=\"http:\/\/www.loba.pt\/\">Loba<\/a>; antes de partir para uma nova aventura, tenho que deixar tudo organizado.<br \/>\nNo entanto, tamb\u00e9m por estes dias, tenho andado entretido \u00e0s ordens do mestre Ro\u00e7as e do pessoal do CCD Porto, na piscina da Senhora da Hora, a preparar-me para mergulhar.<br \/>\nDe m\u00e1scara na cara, botija \u00e0s costas e barbatanas nos p\u00e9s, tenho-me sentido como aqueles peixes que habitam nas paredes dos aqu\u00e1rios.<br \/>\n<a href=\"http:\/\/2.bp.blogspot.com\/-rNdxABdgdgg\/VW1vyK98QgI\/AAAAAAAACM8\/xhYBphLcOwc\/s1600\/mergulho%2B2.jpg\" style=\"clear: left; float: left; margin-bottom: 1em; margin-right: 1em;\"><img decoding=\"async\" border=\"0\" height=\"287\" src=\"http:\/\/2.bp.blogspot.com\/-rNdxABdgdgg\/VW1vyK98QgI\/AAAAAAAACM8\/xhYBphLcOwc\/s320\/mergulho%2B2.jpg\" width=\"320\" \/><\/a>Quero ir para o mar, quero mergulhar e ver vida, quero observar polvos e pequenos peixinhos antes de ir para os mares quentes onde reina o &#8220;peix\u00e3o&#8221;. Ainda n\u00e3o estou pronto mas chegar\u00e1 o dia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8230;a moto tem ficado parada na garagem e o trabalho tem crescido na Loba; antes de partir para uma nova aventura, tenho que deixar tudo organizado. No entanto, tamb\u00e9m por estes dias, tenho andado entretido \u00e0s ordens do mestre Ro\u00e7as e do pessoal do CCD Porto, na piscina da Senhora da Hora, a preparar-me para [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[156,574,52,67,573,572],"tags":[],"featured_image_src":{"landsacpe":false,"list":false,"medium":false,"full":false},"_links":{"self":[{"href":"https:\/\/roadgalaxytouring.com\/index.php\/wp-json\/wp\/v2\/posts\/3828"}],"collection":[{"href":"https:\/\/roadgalaxytouring.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roadgalaxytouring.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/roadgalaxytouring.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/roadgalaxytouring.com\/index.php\/wp-json\/wp\/v2\/comments?post=3828"}],"version-history":[{"count":0,"href":"https:\/\/roadgalaxytouring.com\/index.php\/wp-json\/wp\/v2\/posts\/3828\/revisions"}],"wp:attachment":[{"href":"https:\/\/roadgalaxytouring.com\/index.php\/wp-json\/wp\/v2\/media?parent=3828"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roadgalaxytouring.com\/index.php\/wp-json\/wp\/v2\/categories?post=3828"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roadgalaxytouring.com\/index.php\/wp-json\/wp\/v2\/tags?post=3828"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}