{"id":3833,"date":"2015-05-15T16:59:00","date_gmt":"2015-05-15T16:59:00","guid":{"rendered":"https:\/\/roadgalaxytouring.com\/index.php\/2015\/05\/15\/tempo-de-planear\/"},"modified":"2015-05-15T16:59:00","modified_gmt":"2015-05-15T16:59:00","slug":"tempo-de-planear","status":"publish","type":"post","link":"https:\/\/roadgalaxytouring.com\/index.php\/2015\/05\/15\/tempo-de-planear\/","title":{"rendered":"Tempo de planear"},"content":{"rendered":"<div dir=\"ltr\" style=\"text-align: left;\">\n<a href=\"http:\/\/2.bp.blogspot.com\/-mF7sHQv52Yc\/VVYlXQpJULI\/AAAAAAAACLs\/fBsuN6O9YdE\/s1600\/Mapa%2BEuropa%2BCentral.png\" style=\"clear: left; float: left; margin-bottom: 1em; margin-right: 1em;\"><img decoding=\"async\" border=\"0\" height=\"130\" src=\"http:\/\/2.bp.blogspot.com\/-mF7sHQv52Yc\/VVYlXQpJULI\/AAAAAAAACLs\/fBsuN6O9YdE\/s320\/Mapa%2BEuropa%2BCentral.png\" width=\"320\" \/><\/a>\u00c9 sexta-feira e daqui a pouco saio do escrit\u00f3rio da Loba.<br \/>\nH\u00e1 dias voltei da viagem pela Alemanha, Dinamarca e Su\u00e9cia e, mal cheguei, apetecia-me fazer as malas e partir para outra aventura.<br \/>\nSim, bem sei que n\u00e3o pode ser assim, n\u00e3o h\u00e1 tempo nem dinheiro para tudo mas, se pudesse&#8230;<br \/>\n<a href=\"http:\/\/4.bp.blogspot.com\/-rOvR6s4WHjY\/VVYlXU7vAjI\/AAAAAAAACLw\/tYe0CowI6IY\/s1600\/Mapa%2BCaminho%2Bda%2BPrata.png\" style=\"clear: left; float: left; margin-bottom: 1em; margin-right: 1em;\"><img fetchpriority=\"high\" decoding=\"async\" border=\"0\" height=\"164\" src=\"http:\/\/4.bp.blogspot.com\/-rOvR6s4WHjY\/VVYlXU7vAjI\/AAAAAAAACLw\/tYe0CowI6IY\/s320\/Mapa%2BCaminho%2Bda%2BPrata.png\" width=\"320\" \/><\/a>Com tudo marcado para Agosto: Singapura, Austr\u00e1lia e uns dias na Sui\u00e7a, h\u00e1 que pensar no que fazer antes e depois.<br \/>\nNos pr\u00f3ximos dias irei ver mapas, analisar, pre\u00e7os de hostels, de viagens de avi\u00e3o de aluguer de motos.<br \/>\nIrei matutar, ou ponderar para ser mais correcto para, em princ\u00edpio, tomar a decis\u00e3o mais sensata.<br \/>\nEm cima da mesa est\u00e3o duas hip\u00f3teses: Alemanha, \u00c1ustria, Eslov\u00e1quia, Hungria e Eslov\u00e9nia, moto, sozinho. Saltar de cidade em cidade, conhecendo o que h\u00e1 para conhecer a um ritmo alucinante.<br \/>\nOu parte do Cami\u00f1o de Santiago, Via del Plata. V\u00e1rios dias a p\u00e9, por Espanha, conhecendo qquem passa, pensado na vida, no caminho a seguir no Cami\u00f1o. Aqui iria em grupo. Mas, que grupo, como ir\u00e1 ser?<br \/>\nSe fossem voc\u00eas, o que prefeririam?<\/p>\n<p>&nbsp; &nbsp;&nbsp;<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>\u00c9 sexta-feira e daqui a pouco saio do escrit\u00f3rio da Loba. H\u00e1 dias voltei da viagem pela Alemanha, Dinamarca e Su\u00e9cia e, mal cheguei, apetecia-me fazer as malas e partir para outra aventura. Sim, bem sei que n\u00e3o pode ser assim, n\u00e3o h\u00e1 tempo nem dinheiro para tudo mas, se pudesse&#8230; Com tudo marcado para [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[391,377,387,41,446,583,521,522,88,214,527,52,79,584,94],"tags":[],"featured_image_src":{"landsacpe":false,"list":false,"medium":false,"full":false},"_links":{"self":[{"href":"https:\/\/roadgalaxytouring.com\/index.php\/wp-json\/wp\/v2\/posts\/3833"}],"collection":[{"href":"https:\/\/roadgalaxytouring.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roadgalaxytouring.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/roadgalaxytouring.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/roadgalaxytouring.com\/index.php\/wp-json\/wp\/v2\/comments?post=3833"}],"version-history":[{"count":0,"href":"https:\/\/roadgalaxytouring.com\/index.php\/wp-json\/wp\/v2\/posts\/3833\/revisions"}],"wp:attachment":[{"href":"https:\/\/roadgalaxytouring.com\/index.php\/wp-json\/wp\/v2\/media?parent=3833"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roadgalaxytouring.com\/index.php\/wp-json\/wp\/v2\/categories?post=3833"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roadgalaxytouring.com\/index.php\/wp-json\/wp\/v2\/tags?post=3833"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}