{"id":3858,"date":"2015-03-06T10:23:00","date_gmt":"2015-03-06T10:23:00","guid":{"rendered":"https:\/\/roadgalaxytouring.com\/index.php\/2015\/03\/06\/joao-rebelo-martins-focado-nas-duas-rodas\/"},"modified":"2015-03-06T10:23:00","modified_gmt":"2015-03-06T10:23:00","slug":"joao-rebelo-martins-focado-nas-duas-rodas","status":"publish","type":"post","link":"https:\/\/roadgalaxytouring.com\/index.php\/2015\/03\/06\/joao-rebelo-martins-focado-nas-duas-rodas\/","title":{"rendered":"Jo\u00e3o Rebelo Martins focado nas duas rodas"},"content":{"rendered":"<div dir=\"ltr\" style=\"text-align: left;\">\n<a href=\"http:\/\/3.bp.blogspot.com\/-s6WEHRj0IiY\/VPl_sGf7VTI\/AAAAAAAABIs\/-bakxsQGFU4\/s1600\/SAY_3867%2BPress.jpg\" style=\"clear: left; float: left; margin-bottom: 1em; margin-right: 1em;\"><img fetchpriority=\"high\" decoding=\"async\" border=\"0\" src=\"http:\/\/3.bp.blogspot.com\/-s6WEHRj0IiY\/VPl_sGf7VTI\/AAAAAAAABIs\/-bakxsQGFU4\/s1600\/SAY_3867%2BPress.jpg\" height=\"213\" width=\"320\" \/><\/a>Teve lugar ontem, em Lisboa, em casa do Exmo. Senhor Embaixador do Egipto em Portugal, uma recep\u00e7\u00e3o para diversos convidados, onde o piloto Jo\u00e3o Rebelo Martins teve a oportunidade de contar todas as experi\u00eancias vividas no Cross Egypt Challenge.<br \/>\n<a href=\"http:\/\/3.bp.blogspot.com\/-MYvXblsQ4mc\/VPl_u65tMJI\/AAAAAAAABI0\/S3NLEJfO74Y\/s1600\/Piramide%2BJRM.jpg\" style=\"clear: left; float: left; margin-bottom: 1em; margin-right: 1em;\"><img decoding=\"async\" border=\"0\" src=\"http:\/\/3.bp.blogspot.com\/-MYvXblsQ4mc\/VPl_u65tMJI\/AAAAAAAABI0\/S3NLEJfO74Y\/s1600\/Piramide%2BJRM.jpg\" height=\"213\" width=\"320\" \/><\/a>Perante uma centena de pessoas \u2013 diversos embaixadores, deputados, o Presidente da Federa\u00e7\u00e3o Portuguesa de Motociclismo, Manuel Marinheiro, o Presidente da Assembleia Geral da Federa\u00e7\u00e3o Portuguesa de Motociclismo, Jorge Viegas, o Vice Presidente da Federa\u00e7\u00e3o Portuguesa de Automobilismo e Karting, Paulo Campos, empres\u00e1rios e comunica\u00e7\u00e3o social \u2013 Jo\u00e3o Rebelo Martins falou da viagem que fez em Novembro passado, durante nove dias, percorrendo 3.000 Km por todo o Egypto.<br \/>\n<a href=\"http:\/\/2.bp.blogspot.com\/-wqFRD_asEmo\/VPl_07PiqrI\/AAAAAAAABI8\/xgjHOGX6uxI\/s1600\/CEC%2BVenue%2BPress%2BPhoto.jpg\" style=\"clear: left; float: left; margin-bottom: 1em; margin-right: 1em;\"><img decoding=\"async\" border=\"0\" src=\"http:\/\/2.bp.blogspot.com\/-wqFRD_asEmo\/VPl_07PiqrI\/AAAAAAAABI8\/xgjHOGX6uxI\/s1600\/CEC%2BVenue%2BPress%2BPhoto.jpg\" height=\"213\" width=\"320\" \/><\/a>De Alexandria ao Cairo, passando por Marsa Alan, Aswan, Abu Simbel e Luxor \u2013 citando apenas algumas cidades \u2013 o piloto viu paisagens lind\u00edssimas, visitou monumentos que s\u00e3o patrim\u00f3nio da humanidade, contactou com locais, provou as iguarias eg\u00edpcias e mergulhou no Mar Vermelho. O piloto terminou a sua interven\u00e7\u00e3o com um convite a todos os presentes a visitarem o Egipto porque \u201c al\u00e9m de todos os monumentos e a beleza do deserto, o Egipto \u00e9 um pa\u00eds seguro, com gente simp\u00e1tica e hospitaleira\u201d.<br \/>\nNa recep\u00e7\u00e3o promovida pelo Exmo. Senhor Embaixador do Egipto em Portugal, Jo\u00e3o Rebelo Martins teve ainda oportunidade de expor fotografias de todos os locais que visitou.<br \/>\nExmo. Senhor Embaixador do Egipto em Portugal, na presen\u00e7a do INAC, anunciou a linha a\u00e9rea directa de Lisboa para o Cairo.<br \/>\nSendo Jo\u00e3o Rebelo Martins piloto de competi\u00e7\u00e3o, foi aproveitado o momento para ser desvendado o programa desportivo para 2015. Assim, al\u00e9m de viagens aventura que est\u00e3o a ser programadas para a Europa, Am\u00e9rica e \u00c1frica, o piloto ir\u00e1 realizar o Campeonato Nacional de Cl\u00e1ssicas, com uma Yamaha RD 350 do Team Cl\u00e1ssico Racing.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Teve lugar ontem, em Lisboa, em casa do Exmo. Senhor Embaixador do Egipto em Portugal, uma recep\u00e7\u00e3o para diversos convidados, onde o piloto Jo\u00e3o Rebelo Martins teve a oportunidade de contar todas as experi\u00eancias vividas no Cross Egypt Challenge. Perante uma centena de pessoas \u2013 diversos embaixadores, deputados, o Presidente da Federa\u00e7\u00e3o Portuguesa de Motociclismo, [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[164,41,303,692,52,105,180,645,319],"tags":[],"featured_image_src":{"landsacpe":false,"list":false,"medium":false,"full":false},"_links":{"self":[{"href":"https:\/\/roadgalaxytouring.com\/index.php\/wp-json\/wp\/v2\/posts\/3858"}],"collection":[{"href":"https:\/\/roadgalaxytouring.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roadgalaxytouring.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/roadgalaxytouring.com\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/roadgalaxytouring.com\/index.php\/wp-json\/wp\/v2\/comments?post=3858"}],"version-history":[{"count":0,"href":"https:\/\/roadgalaxytouring.com\/index.php\/wp-json\/wp\/v2\/posts\/3858\/revisions"}],"wp:attachment":[{"href":"https:\/\/roadgalaxytouring.com\/index.php\/wp-json\/wp\/v2\/media?parent=3858"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roadgalaxytouring.com\/index.php\/wp-json\/wp\/v2\/categories?post=3858"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roadgalaxytouring.com\/index.php\/wp-json\/wp\/v2\/tags?post=3858"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}