{"id":3889,"date":"2014-11-14T17:52:00","date_gmt":"2014-11-14T17:52:00","guid":{"rendered":"https:\/\/roadgalaxytouring.com\/index.php\/2014\/11\/14\/14-11-14-alexandria-eln-sokhna\/"},"modified":"2014-11-14T17:52:00","modified_gmt":"2014-11-14T17:52:00","slug":"14-11-14-alexandria-eln-sokhna","status":"publish","type":"post","link":"https:\/\/roadgalaxytouring.com\/index.php\/2014\/11\/14\/14-11-14-alexandria-eln-sokhna\/","title":{"rendered":"14.11.14 &#8211; Alexandria | Eln Sokhna"},"content":{"rendered":"<p><a href=\"http:\/\/2.bp.blogspot.com\/-xtV7yNJR3cM\/VGZAqIV_mDI\/AAAAAAAABbo\/XbHJ15HPw20\/s1600\/paragem%2Bdeserto.jpg\" style=\"clear: left; float: left; margin-bottom: 1em; margin-right: 1em;\"><img fetchpriority=\"high\" decoding=\"async\" border=\"0\" src=\"http:\/\/2.bp.blogspot.com\/-xtV7yNJR3cM\/VGZAqIV_mDI\/AAAAAAAABbo\/XbHJ15HPw20\/s1600\/paragem%2Bdeserto.jpg\" height=\"213\" width=\"320\" \/><\/a>Come\u00e7ou a aventura. At\u00e9 aqui tinham sido dias de prepara\u00e7\u00e3o, perspectiva e, depois da chegada ao Egipto, uma r\u00e1pida adapta\u00e7\u00e3o ao povo eg\u00edpcio e \u00e0 diferen\u00e7a hor\u00e1ria.<br \/>\nHoje come\u00e7ou a s\u00e9rio. E come\u00e7ou com um atraso de hora e meia.<br \/>\nA sa\u00eda de Alexandria foi pelas salinas para, depois, entrarmos numa estrada com pedra solta e afiada; onde tive o receio de cortar algum pneu. Felizmente nada disso aconteceu.<br \/>\nDepois tomamos a Desert Road rumo ao Cairo. Nos quase duzentos quil\u00f3metros que separam Alexandria do Cairo, pela estrada do deserto, deixei cair dois mitos: o primeiro \u00e9 que o deserto \u00e9 bastante ocupado. O segundo \u00e9 que, naquela zona, tinha vegeta\u00e7\u00e3o qb.<br \/>\nA viagem at\u00e9 ao Cairo, numa estrada r\u00e1pida e com longas rectas deu-me sono e perdi a concentra\u00e7\u00e3o algumas vezes. Contudo, chegado \u00e0 metr\u00f3pole eg\u00edpcia, tive que cruzar o tr\u00e2nsito a grande velocidade, o que voltou a colocar a adrenalina em n\u00edveis \u201cnormais\u201d.<br \/>\nO segundo atraso do dia deu-se quando, numa estrada que \u00e9 controlada pelos militares, n\u00e3o nos deixaram passar. Uma hora de conversa\u00e7\u00f5es e depois disso, pudemos seguir viagem. A partir da\u00ed a pol\u00edcia acompanhou grande parte do percurso, excepto no almo\u00e7o: koshary servido no meio do nada.<br \/>\nCom tudo isto chegamos a Eln Sokhna e ao Mar Vermelho quase de n<br \/>\noite.<br \/>\nAmanh\u00e3 o percurso \u00e9 entre o mar e a montanha. Promete!<\/p>\n<div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Come\u00e7ou a aventura. At\u00e9 aqui tinham sido dias de prepara\u00e7\u00e3o, perspectiva e, depois da chegada ao Egipto, uma r\u00e1pida adapta\u00e7\u00e3o ao povo eg\u00edpcio e \u00e0 diferen\u00e7a hor\u00e1ria. Hoje come\u00e7ou a s\u00e9rio. E come\u00e7ou com um atraso de hora e meia. A sa\u00eda de Alexandria foi pelas salinas para, depois, entrarmos numa estrada com pedra solta [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[164,340,343,303,125,335,52,646,807,317,105,645,119],"tags":[],"featured_image_src":{"landsacpe":false,"list":false,"medium":false,"full":false},"_links":{"self":[{"href":"https:\/\/roadgalaxytouring.com\/index.php\/wp-json\/wp\/v2\/posts\/3889"}],"collection":[{"href":"https:\/\/roadgalaxytouring.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roadgalaxytouring.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/roadgalaxytouring.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/roadgalaxytouring.com\/index.php\/wp-json\/wp\/v2\/comments?post=3889"}],"version-history":[{"count":0,"href":"https:\/\/roadgalaxytouring.com\/index.php\/wp-json\/wp\/v2\/posts\/3889\/revisions"}],"wp:attachment":[{"href":"https:\/\/roadgalaxytouring.com\/index.php\/wp-json\/wp\/v2\/media?parent=3889"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roadgalaxytouring.com\/index.php\/wp-json\/wp\/v2\/categories?post=3889"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roadgalaxytouring.com\/index.php\/wp-json\/wp\/v2\/tags?post=3889"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}